{"id":737,"date":"2021-03-06T04:42:39","date_gmt":"2021-03-06T04:42:39","guid":{"rendered":"https:\/\/stakehound.com\/wp-content\/uploads\/2021\/03\/WP_stDASH-Testnet-Banner.png"},"modified":"2021-03-06T04:42:39","modified_gmt":"2021-03-06T04:42:39","slug":"wp_stdash-testnet-banner-2","status":"inherit","type":"attachment","link":"https:\/\/stakehound.com\/es\/wp_stdash-testnet-banner-2\/","title":{"rendered":"WP_stDASH Testnet Banner"},"author":10,"comment_status":"open","ping_status":"closed","template":"","meta":{"content-type":""},"acf":[],"aioseo_notices":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/stakehound.com\/wp-content\/uploads\/2021\/03\/WP_stDASH-Testnet-Banner.png'><img width=\"300\" height=\"150\" src=\"https:\/\/stakehound.com\/wp-content\/uploads\/2021\/03\/WP_stDASH-Testnet-Banner-300x150.png\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/stakehound.com\/wp-content\/uploads\/2021\/03\/WP_stDASH-Testnet-Banner-300x150.png 300w, https:\/\/stakehound.com\/wp-content\/uploads\/2021\/03\/WP_stDASH-Testnet-Banner-1024x512.png 1024w, https:\/\/stakehound.com\/wp-content\/uploads\/2021\/03\/WP_stDASH-Testnet-Banner-768x384.png 768w, https:\/\/stakehound.com\/wp-content\/uploads\/2021\/03\/WP_stDASH-Testnet-Banner.png 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":1200,"height":600,"file":"2021\/03\/WP_stDASH-Testnet-Banner.png","sizes":{"medium":{"file":"WP_stDASH-Testnet-Banner-300x150.png","width":300,"height":150,"mime_type":"image\/png","source_url":"https:\/\/stakehound.com\/wp-content\/uploads\/2021\/03\/WP_stDASH-Testnet-Banner-300x150.png"},"large":{"file":"WP_stDASH-Testnet-Banner-1024x512.png","width":1024,"height":512,"mime_type":"image\/png","source_url":"https:\/\/stakehound.com\/wp-content\/uploads\/2021\/03\/WP_stDASH-Testnet-Banner-1024x512.png"},"thumbnail":{"file":"WP_stDASH-Testnet-Banner-150x150.png","width":150,"height":150,"mime_type":"image\/png","source_url":"https:\/\/stakehound.com\/wp-content\/uploads\/2021\/03\/WP_stDASH-Testnet-Banner-150x150.png"},"medium_large":{"file":"WP_stDASH-Testnet-Banner-768x384.png","width":768,"height":384,"mime_type":"image\/png","source_url":"https:\/\/stakehound.com\/wp-content\/uploads\/2021\/03\/WP_stDASH-Testnet-Banner-768x384.png"},"full":{"file":"WP_stDASH-Testnet-Banner.png","width":1200,"height":600,"mime_type":"image\/png","source_url":"https:\/\/stakehound.com\/wp-content\/uploads\/2021\/03\/WP_stDASH-Testnet-Banner.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/stakehound.com\/wp-content\/uploads\/2021\/03\/WP_stDASH-Testnet-Banner.png","_links":{"self":[{"href":"https:\/\/stakehound.com\/es\/wp-json\/wp\/v2\/media\/737"}],"collection":[{"href":"https:\/\/stakehound.com\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/stakehound.com\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/stakehound.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/stakehound.com\/es\/wp-json\/wp\/v2\/comments?post=737"}]}}